{"id":35552,"date":"2022-09-06T11:59:23","date_gmt":"2022-09-06T09:59:23","guid":{"rendered":"https:\/\/tzp-kupa.hr\/hr\/wp-content\/uploads\/2022\/09\/Demjan-4134.jpg"},"modified":"2022-09-06T11:59:23","modified_gmt":"2022-09-06T09:59:23","slug":"demjan-4134","status":"inherit","type":"attachment","link":"https:\/\/tzp-kupa.hr\/hr\/demjan-4134\/","title":{"rendered":"Demjan-4134"},"author":1,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_links_to":"","_links_to_target":""},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/tzp-kupa.hr\/hr\/wp-content\/uploads\/2022\/09\/Demjan-4134.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/tzp-kupa.hr\/hr\/wp-content\/uploads\/2022\/09\/Demjan-4134-600x400.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/tzp-kupa.hr\/hr\/wp-content\/uploads\/2022\/09\/Demjan-4134-600x400.jpg 600w, https:\/\/tzp-kupa.hr\/hr\/wp-content\/uploads\/2022\/09\/Demjan-4134-1200x800.jpg 1200w, https:\/\/tzp-kupa.hr\/hr\/wp-content\/uploads\/2022\/09\/Demjan-4134-768x512.jpg 768w, https:\/\/tzp-kupa.hr\/hr\/wp-content\/uploads\/2022\/09\/Demjan-4134-1536x1024.jpg 1536w, https:\/\/tzp-kupa.hr\/hr\/wp-content\/uploads\/2022\/09\/Demjan-4134.jpg 1920w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1920,"height":1280,"file":"2022\/09\/Demjan-4134.jpg","sizes":{"medium":{"file":"Demjan-4134-600x400.jpg","width":600,"height":400,"filesize":68154,"mime_type":"image\/jpeg","source_url":"https:\/\/tzp-kupa.hr\/hr\/wp-content\/uploads\/2022\/09\/Demjan-4134-600x400.jpg"},"large":{"file":"Demjan-4134-1200x800.jpg","width":1200,"height":800,"filesize":231727,"mime_type":"image\/jpeg","source_url":"https:\/\/tzp-kupa.hr\/hr\/wp-content\/uploads\/2022\/09\/Demjan-4134-1200x800.jpg"},"thumbnail":{"file":"Demjan-4134-280x280.jpg","width":280,"height":280,"filesize":25471,"mime_type":"image\/jpeg","source_url":"https:\/\/tzp-kupa.hr\/hr\/wp-content\/uploads\/2022\/09\/Demjan-4134-280x280.jpg"},"medium_large":{"file":"Demjan-4134-768x512.jpg","width":768,"height":512,"filesize":106266,"mime_type":"image\/jpeg","source_url":"https:\/\/tzp-kupa.hr\/hr\/wp-content\/uploads\/2022\/09\/Demjan-4134-768x512.jpg"},"1536x1536":{"file":"Demjan-4134-1536x1024.jpg","width":1536,"height":1024,"filesize":351563,"mime_type":"image\/jpeg","source_url":"https:\/\/tzp-kupa.hr\/hr\/wp-content\/uploads\/2022\/09\/Demjan-4134-1536x1024.jpg"},"full":{"file":"Demjan-4134.jpg","width":1920,"height":1280,"mime_type":"image\/jpeg","source_url":"https:\/\/tzp-kupa.hr\/hr\/wp-content\/uploads\/2022\/09\/Demjan-4134.jpg"}},"image_meta":{"aperture":"2.8","credit":"","camera":"Canon EOS 5D Mark IV","caption":"","created_timestamp":"1662216003","copyright":"","focal_length":"70","iso":"100","shutter_speed":"0.00125","title":"","orientation":"0","keywords":[]},"filesize":505058},"post":null,"source_url":"https:\/\/tzp-kupa.hr\/hr\/wp-content\/uploads\/2022\/09\/Demjan-4134.jpg","_links":{"self":[{"href":"https:\/\/tzp-kupa.hr\/hr\/wp-json\/wp\/v2\/media\/35552"}],"collection":[{"href":"https:\/\/tzp-kupa.hr\/hr\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/tzp-kupa.hr\/hr\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/tzp-kupa.hr\/hr\/wp-json\/wp\/v2\/users\/1"}]}}